{"id":78333,"date":"2026-06-01T13:51:56","date_gmt":"2026-06-01T11:51:56","guid":{"rendered":"https:\/\/ekayana-institut.de\/mediathek\/praxis-des-gleichmutes-upekkha-mit-den-unsicherheiten-des-lebens-umgehen\/"},"modified":"2026-06-01T13:51:56","modified_gmt":"2026-06-01T11:51:56","slug":"praxis-des-gleichmutes-upekkha-mit-den-unsicherheiten-des-lebens-umgehen","status":"publish","type":"mediathek","link":"https:\/\/ekayana-institut.de\/fr\/mediathek\/praxis-des-gleichmutes-upekkha-mit-den-unsicherheiten-des-lebens-umgehen\/","title":{"rendered":"Praxis des Gleichmutes &#8211; Upekkh\u0101: Mit den Unsicherheiten des Lebens umgehen"},"template":"","mediathek-consecutive":[],"mediathek-simultaneous":[],"transcript":[],"mediathek-type-of-teching":[],"mediathek-location":[29],"mediathek-serie":[],"mediathek-other":[71,31],"mediathek-topic":[534,87,49,48,644,57],"mediathek-language":[51],"mediathek-year":[738],"teacher":[59],"mediathek-type":[33],"class_list":["post-78333","mediathek","type-mediathek","status-publish","hentry","mediathek-location-gruener-baum","mediathek-other-new","mediathek-other-suitable-for-beginners","mediathek-topic-abhidharma","mediathek-topic-classic-buddhism","mediathek-topic-general-dharma","mediathek-topic-mahamudra","mediathek-topic-shamata","mediathek-topic-vipassana","mediathek-language-deutsch","mediathek-year-738","teacher-lama-lhundrup","mediathek-type-video"],"meta_box":{"mediathek-title-text":"Praxis des Gleichmutes - Upekkh\u0101: Mit den Unsicherheiten des Lebens umgehen","mediathek-episoden-title-text":"","mediathek-teacher-text":[{"term_id":59,"name":"Lama Lhundrup","slug":"lama-lhundrup","term_group":0,"term_taxonomy_id":59,"taxonomy":"teacher","description":"","parent":0,"count":792,"filter":"raw","term_order":"0"}],"mediathek-year-number":[{"term_id":738,"name":"2026","slug":"2026","term_group":0,"term_taxonomy_id":738,"taxonomy":"mediathek-year","description":"","parent":0,"count":14,"filter":"raw","term_order":"0"}],"mediathek-location-text":[{"term_id":29,"name":"Gr\u00fcner Baum","slug":"gruener-baum","term_group":0,"term_taxonomy_id":29,"taxonomy":"mediathek-location","description":"","parent":0,"count":303,"filter":"raw","term_order":"0"}],"mediathek-language-text":[{"term_id":51,"name":"Deutsch","slug":"deutsch","term_group":0,"term_taxonomy_id":51,"taxonomy":"mediathek-language","description":"","parent":0,"count":509,"filter":"raw","term_order":"0"}],"mediathek-original-or-translation-text":"Original language","mediathek-type-text":[{"term_id":33,"name":"Video","slug":"video","term_group":0,"term_taxonomy_id":33,"taxonomy":"mediathek-type","description":"","parent":0,"count":186,"filter":"raw","term_order":"0"}],"mediathek-topics-text":[{"term_id":48,"name":"Mahamudra","slug":"mahamudra","term_group":0,"term_taxonomy_id":48,"taxonomy":"mediathek-topic","description":"","parent":0,"count":283,"filter":"raw","term_order":"0"},{"term_id":49,"name":"General Dharma","slug":"general-dharma","term_group":0,"term_taxonomy_id":49,"taxonomy":"mediathek-topic","description":"","parent":0,"count":256,"filter":"raw","term_order":"0"},{"term_id":57,"name":"Vipassana","slug":"vipassana","term_group":0,"term_taxonomy_id":57,"taxonomy":"mediathek-topic","description":"","parent":0,"count":206,"filter":"raw","term_order":"0"},{"term_id":87,"name":"Classic Buddhism","slug":"classic-buddhism","term_group":0,"term_taxonomy_id":87,"taxonomy":"mediathek-topic","description":"","parent":0,"count":172,"filter":"raw","term_order":"0"},{"term_id":534,"name":"Abhidharma","slug":"abhidharma","term_group":0,"term_taxonomy_id":534,"taxonomy":"mediathek-topic","description":"","parent":0,"count":38,"filter":"raw","term_order":"0"},{"term_id":644,"name":"Shamata","slug":"shamata","term_group":0,"term_taxonomy_id":644,"taxonomy":"mediathek-topic","description":"","parent":0,"count":22,"filter":"raw","term_order":"0"}],"mediathek-keywords-text":"","mediathek-type-of-teaching-text":[],"mediathek-other":[{"term_id":31,"name":"Suitable for Beginners","slug":"suitable-for-beginners","term_group":0,"term_taxonomy_id":31,"taxonomy":"mediathek-other","description":"","parent":0,"count":222,"filter":"raw","term_order":"0"},{"term_id":71,"name":"New","slug":"new","term_group":0,"term_taxonomy_id":71,"taxonomy":"mediathek-other","description":"","parent":0,"count":38,"filter":"raw","term_order":"0"}],"mediathek-summary-text":"<p>Wie kann die <strong>Praxis des Gleichmuts<\/strong> helfen, mit den Unsicherheiten des Lebens umzugehen? <strong>Lama Tilmann Lh\u00fcndrup<\/strong> unterscheidet in diesem Vortrag zwischen einem k\u00fcnstlichen Gleichmut \u2013 der blo\u00dfen \u00dcbung in Geduld und Gelassenheit \u2013 und dem tiefen, authentischen Gleichmut, der aus echter Seinserkenntnis und Weisheit entsteht.<\/p>\n\n<p><strong>Darum geht es in diesem Video:<\/strong><\/p>\n\n<p>Echter Gleichmut bedeutet nicht, \u00c4ngste wegzumachen oder zu unterdr\u00fccken. Es geht darum, mitten in der Angst zu sein und zu erkennen, dass Gedanken und Emotionen keine wirkliche Substanz haben. Lama Tilmann zeigt, wie ein offenes, entspanntes Gewahrsein auch inmitten von Krisen, Leid und Unsicherheit m\u00f6glich ist \u2013 nicht durch Selbstsuggestion, sondern durch gelebte Einsicht in die Natur des Geistes.<\/p>\n\n<p><strong>Themen:<\/strong><\/p>\n\n<ul>\n<li>K\u00fcnstlicher vs. authentischer Gleichmut<\/li>\n<li>Wie \u00c4ngste entstehen und was ihnen Kraft gibt<\/li>\n<li>Die Rolle von Seinserkenntnis und Weisheit in der buddhistischen Praxis<\/li>\n<li>Gleichmut als aktives, herzoffenes Sein \u2013 nicht als passives Nichtstun<\/li>\n<li>Wie Leid und innere Freiheit gleichzeitig erfahrbar sind<\/li>\n<\/ul>","mediathek-co-teachers-text":"","mediathek-source_text-text":"","mediathek-author_of_source_text-text":"","related_texts-wysiwyg":"","mediathek-series_name-text":[],"mediathek-simultaneous-translation-id-text":false,"mediathek-consecutive_translation_id-text":false,"mediathek-transcript_id-text":[],"mediathek-streaming_link-url":"https:\/\/www.youtube.com\/watch?v=cppPoxZxqHI","mediathek-Embedding-Code":"","mediathek-video_download_link-url":"","mediathek-additional-information":"","mediathek-additional_link":"","mediathek-size-audio-text":"","mediathek-size-text-text":"","mediathek-size-video-text":"","mediathek-length-timepicker":"00:09:40","mediathek-audio_download_link-url":"","mediathek-text_download_link-url":"","mediathek-unique-ID-number":""},"_links":{"self":[{"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek\/78333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek"}],"about":[{"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/types\/mediathek"}],"wp:attachment":[{"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/media?parent=78333"}],"wp:term":[{"taxonomy":"mediathek-consecutive","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-consecutive?post=78333"},{"taxonomy":"mediathek-simultaneous","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-simultaneous?post=78333"},{"taxonomy":"transcript","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/transcript?post=78333"},{"taxonomy":"mediathek-type-of-teching","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-type-of-teching?post=78333"},{"taxonomy":"mediathek-location","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-location?post=78333"},{"taxonomy":"mediathek-serie","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-serie?post=78333"},{"taxonomy":"mediathek-other","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-other?post=78333"},{"taxonomy":"mediathek-topic","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-topic?post=78333"},{"taxonomy":"mediathek-language","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-language?post=78333"},{"taxonomy":"mediathek-year","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-year?post=78333"},{"taxonomy":"teacher","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/teacher?post=78333"},{"taxonomy":"mediathek-type","embeddable":true,"href":"https:\/\/ekayana-institut.de\/fr\/wp-json\/wp\/v2\/mediathek-type?post=78333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}